{"id":6155,"date":"2025-09-11T02:41:13","date_gmt":"2025-09-11T02:41:13","guid":{"rendered":"https:\/\/dev.mediumterm.ch\/\/listing\/central-love\/"},"modified":"2026-09-02T03:00:47","modified_gmt":"2026-09-02T03:00:47","slug":"central-love","status":"publish","type":"listing","link":"https:\/\/mediumterm.ch\/de\/listing\/central-love\/","title":{"rendered":"Zentrales Liebesapartment mit Terrasse und Parkplatz"},"content":{"rendered":"<p>Entdecken Sie die Seestadt Lugano, ihre wundersch\u00f6nen Str\u00e4nde und faszinierenden Umpromenaden von diesem Apartment mit zwei Schlafzimmern aus.<br \/>\n\u00a0<br \/>\nDie zentralbeheizte Wohnung im dritten Stock eines f\u00fcnfst\u00f6ckigen Geb\u00e4udes verf\u00fcgt \u00fcber ein Wohnzimmer mit Zugang zur Terrasse. Das Wohnzimmer ist mit einem Sofa und einem Esstisch ausgestattet. Zudem gibt es eine offene K\u00fcche mit Einbauk\u00fcche. Diese ist mit einer Sp\u00fclmaschine, einer Kaffeemaschine, einer Mikrowelle, einem Backofen, einem Induktionskochfeld, einem Toaster und einem K\u00fchlschrank mit Gefrierfach ausgestattet.<br \/>\n\u00a0<br \/>\nG\u00e4ste k\u00f6nnen auch auf der Terrasse unter freiem Himmel speisen.<br \/>\n\u00a0<br \/>\nSchlafen<br \/>\n\u00a0<br \/>\nSchlafzimmer 1: Das ordentlich gestaltete Zimmer verf\u00fcgt \u00fcber ein Doppelbett und einen Kleiderschrank.<br \/>\nSchlafzimmer 2: Das einfache Schlafzimmer verf\u00fcgt \u00fcber ein Doppelbett und einen Kleiderschrank.<br \/>\n\u00a0<br \/>\nBadezimmer<br \/>\n\u00a0<br \/>\nBadezimmer 1: Das moderne Badezimmer verf\u00fcgt \u00fcber eine Dusche, ein Waschbecken und ein WC<br \/>\n\u00a0<br \/>\nZus\u00e4tzlich<br \/>\n\u00a0<br \/>\n\u2022 Kinderfreundliche Wohnung \u2022 Ruhige Lage \u2022 Haustiere erlaubt \u2022 Privatparkplatz \u2022 Haartrockner \u2022 Fahrstuhl \u2022 Kostenloses WLAN<\/p>\n<p>\u00a0<br \/>\nStandort<br \/>\n\u00a0<br \/>\nDie Wohnung ist ideal gelegen f\u00fcr einen entspannten und erlebnisreichen Urlaub im Ferienort Lugano. Sie ist kaum einen Kilometer vom Luganersee und seiner malerischen Uferpromenade entfernt. Das etwa 9 Minuten von hier entfernte historische Stadtzentrum bietet zahlreiche Renaissance- und Barockkirchen, Arkadenpl\u00e4tze und andere sehenswerte Denkm\u00e4ler. Lugano ist auch bekannt f\u00fcr seine Parks am Seeufer und den Blick auf den Monte Br\u00e8 und den Monte San Salvatore. Da die Stadt ein gut entwickeltes touristisches Zentrum ist, gibt es hier zahlreiche Einkaufsm\u00f6glichkeiten mit lokalen und internationalen Marken. Im Umkreis von 500 Metern um das Haus befinden sich zahlreiche Restaurants, Imbisse, Gesch\u00e4fte, Superm\u00e4rkte und eine Apotheke. Ein Golfplatz und ein Tennisclub sind etwa 3 Kilometer bzw. 2 Kilometer von der Wohnung entfernt. Der n\u00e4chste Bahnhof ist etwa 4 Autominuten von hier entfernt. Der n\u00e4chste internationale Flughafen ist etwa eine Autostunde entfernt.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Explore the lake town of Lugano, its beautiful beaches and mesmerizing lakefronts from this two-bedroom apartment. \u00a0 The centrally-heated apartment on the third floor of a five-storey building has a living room with access to the terrace. The living room has a sofa and a dining table. There is also an open kitchen with modular [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":7725,"parent":0,"menu_order":0,"template":"","listing_type":[62],"room_type":[254],"amenities":[1195,1192,1191,1148,1183,1182,1179,1205,1186,1189,1199,1164,1165,1188,1169,1153,1152,1143,1163,1190,1151,1147],"facilities":[1120,1101,1121,1103],"listing_countries":[1024],"listing_states":[1023,1070],"listing_cities":[944],"listing_areas":[1060],"class_list":["post-6155","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_type-apartment","room_type-entire-place","listing_amenity-coffee-machine","listing_amenity-dishwasher","listing_amenity-electric-kettle","listing_amenity-free-wifi","listing_amenity-freezer","listing_amenity-fridge","listing_amenity-full-kitchen","listing_amenity-hair-dryer","listing_amenity-induction-hob","listing_amenity-microwave","listing_amenity-other-coffee-machine","listing_amenity-outdoor-dining-area","listing_amenity-outdoor-table-chairs","listing_amenity-oven","listing_amenity-quiet-area","listing_amenity-satellite-tv","listing_amenity-smart-tv","listing_amenity-smoking-not-permitted","listing_amenity-terrace","listing_amenity-toaster","listing_amenity-tv","listing_amenity-wifi","listing_facility-car-not-necessary","listing_facility-elevator","listing_facility-in-town","listing_facility-private-parking-space","listing_country-switzerland","listing_state-distretto-di-lugano","listing_state-ticino","listing_city-lugano","listing_area-molino-nuovo"],"_links":{"self":[{"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listings\/6155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listings"}],"about":[{"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/users\/30"}],"version-history":[{"count":4,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listings\/6155\/revisions"}],"predecessor-version":[{"id":13516,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listings\/6155\/revisions\/13516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/media\/7725"}],"wp:attachment":[{"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/media?parent=6155"}],"wp:term":[{"taxonomy":"listing_type","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listing_type?post=6155"},{"taxonomy":"room_type","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/room_type?post=6155"},{"taxonomy":"listing_amenity","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/amenities?post=6155"},{"taxonomy":"listing_facility","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/facilities?post=6155"},{"taxonomy":"listing_country","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listing_countries?post=6155"},{"taxonomy":"listing_state","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listing_states?post=6155"},{"taxonomy":"listing_city","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listing_cities?post=6155"},{"taxonomy":"listing_area","embeddable":true,"href":"https:\/\/mediumterm.ch\/de\/wp-json\/wp\/v2\/listing_areas?post=6155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}